{"id":7075,"date":"2026-07-14T08:56:31","date_gmt":"2026-07-14T06:56:31","guid":{"rendered":"https:\/\/velo-utile.fr\/site\/?p=7075"},"modified":"2026-07-14T08:57:33","modified_gmt":"2026-07-14T06:57:33","slug":"festival-le-mille-2026","status":"publish","type":"post","link":"https:\/\/velo-utile.fr\/site\/2026\/07\/festival-le-mille-2026\/","title":{"rendered":"Festival Le Mille 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019atelier de V\u00e9lo Utile s\u2019installera au Mille les samedi 22 et dimanche 23 ao\u00fbt dans la vall\u00e9e de Gou\u00ebdic \u00e0 Saint Brieuc. <\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/le-mille.org\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"445\" data-src=\"https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-1-1024x445.png\" alt=\"\" class=\"wp-image-7078 lazyload\" data-srcset=\"https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-1-1024x445.png 1024w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-1-300x130.png 300w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-1-768x334.png 768w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-1.png 1157w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/445;\" \/><\/a><\/figure>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"640\" height=\"640\" data-src=\"https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image.png\" alt=\"\" class=\"wp-image-7076 lazyload\" data-srcset=\"https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image.png 640w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-300x300.png 300w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-150x150.png 150w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-270x270.png 270w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/image-230x230.png 230w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 640px; --smush-placeholder-aspect-ratio: 640\/640;\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> Une cha\u00eene qui saute, un frein \u00e0 r\u00e9gler ou une selle \u00e0 ajuster ? Les b\u00e9n\u00e9voles seront l\u00e0 pour effectuer de petites r\u00e9parations, prodiguer des conseils pratiques et partager de nombreuses astuces pour rouler plus sereinement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019occasion \u00e9galement d\u2019\u00e9changer autour de la mobilit\u00e9 active, des bonnes pratiques \u00e0 adopter et des consignes essentielles de s\u00e9curit\u00e9 \u00e0 v\u00e9lo, afin que chacun puisse p\u00e9daler en toute confiance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un parking v\u00e9lo sera mis en place par l&rsquo;organisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/le-mille.org\/programme\/\">Le programme du Mille 2026<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/le-mille.org\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"389\" data-src=\"https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/Mille-viaduc-1024x389.png\" alt=\"\" class=\"wp-image-7079 lazyload\" data-srcset=\"https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/Mille-viaduc-1024x389.png 1024w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/Mille-viaduc-300x114.png 300w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/Mille-viaduc-768x292.png 768w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/Mille-viaduc-1536x583.png 1536w, https:\/\/velo-utile.fr\/site\/wp-content\/uploads\/2026\/07\/Mille-viaduc.png 1722w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/389;\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019atelier de V\u00e9lo Utile s\u2019installera au Mille les samedi 22 et dimanche 23 ao\u00fbt dans la vall\u00e9e de Gou\u00ebdic \u00e0 Saint Brieuc.<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60,65,4],"tags":[],"class_list":["post-7075","post","type-post","status-publish","format-standard","hentry","category-actu","category-animations","category-atelier"],"_links":{"self":[{"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/posts\/7075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/comments?post=7075"}],"version-history":[{"count":2,"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/posts\/7075\/revisions"}],"predecessor-version":[{"id":7081,"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/posts\/7075\/revisions\/7081"}],"wp:attachment":[{"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/media?parent=7075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/categories?post=7075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/velo-utile.fr\/site\/wp-json\/wp\/v2\/tags?post=7075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}